{"id":730,"date":"2023-07-27T11:23:33","date_gmt":"2023-07-27T11:23:33","guid":{"rendered":"http:\/\/bck.rtv-ooe.at\/rtvmeinverein\/?p=730"},"modified":"2023-08-11T21:43:13","modified_gmt":"2023-08-11T21:43:13","slug":"todliche-hitze-klimahysterie-in-den-medien","status":"publish","type":"post","link":"https:\/\/www.rtvmeinverein.at\/index.php\/2023\/07\/27\/todliche-hitze-klimahysterie-in-den-medien\/","title":{"rendered":"T\u00f6dliche Hitze: Klimahysterie in den Medien"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.rtvmeinverein.at\/wp-content\/uploads\/2023\/07\/Fire_behavior_on_the_Mangum_Fire.jpg\" alt=\"\" class=\"wp-image-731\" width=\"560\" height=\"315\"\/><\/figure>\n\n\n\n<p>Wenn man etablierten Medienh\u00e4usern Glauben schenken w\u00fcrde, g\u00e4be es unsere Erde nicht mehr sehr lange. Von brennenden St\u00e4dten und t\u00f6dlicher Hitze ist die Rede, dabei waren die ersten Monate dieses Jahres k\u00e4lter als im Durchschnitt und dennoch wird die Klimahysterie vorangetrieben. Mittlerweile stehen sogar Klimalockdowns im Raum. Das Klima scheint f\u00fcr Politik und Medien also nach Corona eine neue M\u00f6glichkeit darzustellen, um die Menschen in Angst und Schrecken versetzen zu k\u00f6nnen. <\/p>\n\n\n\n<p><a href=\"https:\/\/tkp.at\/2023\/07\/19\/die-klimahysterie-der-medien-bringt-uns-um\/\" target=\"_blank\" rel=\"noreferrer noopener\">Die Klimahysterie der Medien bringt uns um (tkp.at)<\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Rhodos: Gelegter Waldbrand eng begrenzt\" width=\"1170\" height=\"658\" src=\"https:\/\/www.youtube.com\/embed\/XAatxCdlaTM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Wenn man etablierten Medienh\u00e4usern Glauben schenken w\u00fcrde, g\u00e4be es unsere Erde nicht mehr sehr lange. Von brennenden St\u00e4dten und t\u00f6dlicher Hitze ist die Rede, dabei waren die ersten Monate dieses Jahres k\u00e4lter als im Durchschnitt und dennoch wird die Klimahysterie vorangetrieben. Mittlerweile stehen sogar Klimalockdowns im Raum. Das Klima scheint f\u00fcr Politik und Medien also [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":731,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[17],"tags":[],"_links":{"self":[{"href":"https:\/\/www.rtvmeinverein.at\/index.php\/wp-json\/wp\/v2\/posts\/730"}],"collection":[{"href":"https:\/\/www.rtvmeinverein.at\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rtvmeinverein.at\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rtvmeinverein.at\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rtvmeinverein.at\/index.php\/wp-json\/wp\/v2\/comments?post=730"}],"version-history":[{"count":2,"href":"https:\/\/www.rtvmeinverein.at\/index.php\/wp-json\/wp\/v2\/posts\/730\/revisions"}],"predecessor-version":[{"id":1120,"href":"https:\/\/www.rtvmeinverein.at\/index.php\/wp-json\/wp\/v2\/posts\/730\/revisions\/1120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rtvmeinverein.at\/index.php\/wp-json\/wp\/v2\/media\/731"}],"wp:attachment":[{"href":"https:\/\/www.rtvmeinverein.at\/index.php\/wp-json\/wp\/v2\/media?parent=730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rtvmeinverein.at\/index.php\/wp-json\/wp\/v2\/categories?post=730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rtvmeinverein.at\/index.php\/wp-json\/wp\/v2\/tags?post=730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}